{"id":1131,"date":"2016-04-28T16:35:07","date_gmt":"2016-04-28T14:35:07","guid":{"rendered":"https:\/\/portesdesiris.wordpress.com\/?p=1131"},"modified":"2020-02-05T08:30:36","modified_gmt":"2020-02-05T07:30:36","slug":"votre-soiree-dentreprise-a-theme-aux-portes-des-iris","status":"publish","type":"post","link":"https:\/\/portesdesiris.ch\/en\/votre-soiree-dentreprise-a-theme-aux-portes-des-iris\/","title":{"rendered":"Exp\u00e9rimentez la nuit polaire spectaculaire aux Portes des Iris"},"content":{"rendered":"<p>Quoi de mieux qu&#8217;un d\u00e9cor hivernal et nordique pour\u00a0votre soir\u00e9e de fin d&#8217;ann\u00e9e?\u00a0Aux Portes des Iris, nous vous proposons un environnement\u00a0et une ambiance unique.<\/p>\n<p>Imaginez une sc\u00e9nographie tout droit sortie de la Reine des Neiges ou presque.<\/p>\n<p style=\"text-align: justify;\">Arriv\u00e9s par la cour dans une for\u00eat de sapins parsem\u00e9e de lumignons givr\u00e9s, vous vous trouverez nez \u00e0 nez avec de beaux animaux \u00e0 la fourrure flamboyante; ours polaires, renards blancs, loups arctiques et pingouins vous donneront l\u2019impression de faire un voyage dans une r\u00e9gion hors du temps.<\/p>\n<p style=\"text-align: justify;\">Des jongleurs sur \u00e9chasses et cracheurs de feu vous raviront par leur spectacle impressionnant. Vous pourrez vous r\u00e9chauffer autour d\u2019un bras\u00e9ro aux saveurs d\u2019un vin chaud \u00e9pic\u00e9.<\/p>\n<p style=\"text-align: justify;\">\u00c0 l\u2019int\u00e9rieur, neige et glace seront \u00e0 l\u2019honneur. Quelques peaux de b\u00eates et un feu chatoyant vous feront \u00ab\u00a0glisser\u00a0\u00bb dans cette ambiance unique et magique\u00a0!<\/p>\n<p>De l&#8217;art de la table, en passant par la gastronomie, la d\u00e9coration et les diverses animations, votre soir\u00e9e restera grav\u00e9e dans les m\u00e9moires.<\/p>\n<p style=\"text-align: center;\"><iframe loading=\"lazy\" src=\"https:\/\/player.vimeo.com\/video\/76942734\" width=\"640\" height=\"360\" frameborder=\"0\" allowfullscreen=\"allowfullscreen\"><\/iframe><\/p>\n<p>Vos convives repartiront des \u00e9toiles plein les yeux!<\/p>\n<p>Nous avons r\u00e9alis\u00e9 plus d&#8217;une soir\u00e9e polaire, vous trouverez un aper\u00e7u gr\u00e2ce aux photos ci-dessous :<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-9003 size-full\" src=\"https:\/\/portesdesiris.ch\/wp-content\/uploads\/2020\/01\/portes-des-iris5-soiree-polaire.jpg\" alt=\"Nuit polaire aux Portes des Iris.\" width=\"1000\" height=\"667\" srcset=\"https:\/\/portesdesiris.ch\/wp-content\/uploads\/2020\/01\/portes-des-iris5-soiree-polaire.jpg 1000w, https:\/\/portesdesiris.ch\/wp-content\/uploads\/2020\/01\/portes-des-iris5-soiree-polaire-300x200.jpg 300w, https:\/\/portesdesiris.ch\/wp-content\/uploads\/2020\/01\/portes-des-iris5-soiree-polaire-768x512.jpg 768w\" sizes=\"auto, (max-width: 1000px) 100vw, 1000px\" \/><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-9000 size-full\" src=\"https:\/\/portesdesiris.ch\/wp-content\/uploads\/2020\/01\/portes-des-iris4-soiree-polaire.jpg\" alt=\"Nuit polaire aux Portes des Iris.\" width=\"1000\" height=\"750\" srcset=\"https:\/\/portesdesiris.ch\/wp-content\/uploads\/2020\/01\/portes-des-iris4-soiree-polaire.jpg 1000w, https:\/\/portesdesiris.ch\/wp-content\/uploads\/2020\/01\/portes-des-iris4-soiree-polaire-300x225.jpg 300w, https:\/\/portesdesiris.ch\/wp-content\/uploads\/2020\/01\/portes-des-iris4-soiree-polaire-768x576.jpg 768w\" sizes=\"auto, (max-width: 1000px) 100vw, 1000px\" \/><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-8997 size-full\" src=\"https:\/\/portesdesiris.ch\/wp-content\/uploads\/2020\/01\/portes-des-iris3-soiree-polaire.jpg\" alt=\"Nuit polaire aux Portes des Iris.\" width=\"1000\" height=\"750\" srcset=\"https:\/\/portesdesiris.ch\/wp-content\/uploads\/2020\/01\/portes-des-iris3-soiree-polaire.jpg 1000w, https:\/\/portesdesiris.ch\/wp-content\/uploads\/2020\/01\/portes-des-iris3-soiree-polaire-300x225.jpg 300w, https:\/\/portesdesiris.ch\/wp-content\/uploads\/2020\/01\/portes-des-iris3-soiree-polaire-768x576.jpg 768w\" sizes=\"auto, (max-width: 1000px) 100vw, 1000px\" \/><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-8994 size-full\" src=\"https:\/\/portesdesiris.ch\/wp-content\/uploads\/2020\/01\/portes-des-iris2-soiree-polaire.jpg\" alt=\"Nuit polaire aux Portes des Iris.\" width=\"1000\" height=\"750\" srcset=\"https:\/\/portesdesiris.ch\/wp-content\/uploads\/2020\/01\/portes-des-iris2-soiree-polaire.jpg 1000w, https:\/\/portesdesiris.ch\/wp-content\/uploads\/2020\/01\/portes-des-iris2-soiree-polaire-300x225.jpg 300w, https:\/\/portesdesiris.ch\/wp-content\/uploads\/2020\/01\/portes-des-iris2-soiree-polaire-768x576.jpg 768w\" sizes=\"auto, (max-width: 1000px) 100vw, 1000px\" \/><\/p>\n<p>Laissez la magie op\u00e9rer&#8230; Contactez-nous pour obtenir le dossier complet.<\/p>\n<p>Notre partenaire d\u00e9coration et location de mobilier: <a href=\"https:\/\/planitswiss.com\">Planitswiss<\/a> et <a href=\"https:\/\/www.swisseventrentals.com\">Swiss Event Rental<\/a>.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Quoi de mieux qu&#8217;un d\u00e9cor hivernal et nordique pour\u00a0votre soir\u00e9e de fin d&#8217;ann\u00e9e?\u00a0Aux Portes des Iris, nous vous proposons un environnement\u00a0et une ambiance unique. Imaginez une sc\u00e9nographie tout droit sortie de la Reine des Neiges ou presque. Arriv\u00e9s par la cour dans une for\u00eat de sapins parsem\u00e9e de lumignons givr\u00e9s, vous vous trouverez nez \u00e0 [&hellip;]<\/p>\n","protected":false},"author":6,"featured_media":9007,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[1,14,21,32],"tags":[],"class_list":["post-1131","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-blog","category-companies","category-evenements","category-thematiques"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Exp\u00e9rimentez la nuit polaire spectaculaire aux Portes des Iris - Portes des Iris<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/portesdesiris.ch\/de\/votre-soiree-dentreprise-a-theme-aux-portes-des-iris\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Exp\u00e9rimentez la nuit polaire spectaculaire aux Portes des Iris - Portes des Iris\" \/>\n<meta property=\"og:description\" content=\"Quoi de mieux qu&#8217;un d\u00e9cor hivernal et nordique pour\u00a0votre soir\u00e9e de fin d&#8217;ann\u00e9e?\u00a0Aux Portes des Iris, nous vous proposons un environnement\u00a0et une ambiance unique. Imaginez une sc\u00e9nographie tout droit sortie de la Reine des Neiges ou presque. Arriv\u00e9s par la cour dans une for\u00eat de sapins parsem\u00e9e de lumignons givr\u00e9s, vous vous trouverez nez \u00e0 [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/portesdesiris.ch\/de\/votre-soiree-dentreprise-a-theme-aux-portes-des-iris\/\" \/>\n<meta property=\"og:site_name\" content=\"Portes des Iris\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/portesdesiris\/\" \/>\n<meta property=\"article:published_time\" content=\"2016-04-28T14:35:07+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2020-02-05T07:30:36+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/portesdesiris.ch\/wp-content\/uploads\/2016\/04\/1202_PdIR_5837-scaled.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1920\" \/>\n\t<meta property=\"og:image:height\" content=\"1280\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Portes des Iris\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Portes des Iris\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/portesdesiris.ch\\\/de\\\/votre-soiree-dentreprise-a-theme-aux-portes-des-iris\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/portesdesiris.ch\\\/de\\\/votre-soiree-dentreprise-a-theme-aux-portes-des-iris\\\/\"},\"author\":{\"name\":\"Portes des Iris\",\"@id\":\"https:\\\/\\\/portesdesiris.ch\\\/de\\\/#\\\/schema\\\/person\\\/1fec589d003851c4ffe308e8071bffeb\"},\"headline\":\"Exp\u00e9rimentez la nuit polaire spectaculaire aux Portes des Iris\",\"datePublished\":\"2016-04-28T14:35:07+00:00\",\"dateModified\":\"2020-02-05T07:30:36+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/portesdesiris.ch\\\/de\\\/votre-soiree-dentreprise-a-theme-aux-portes-des-iris\\\/\"},\"wordCount\":246,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/portesdesiris.ch\\\/de\\\/votre-soiree-dentreprise-a-theme-aux-portes-des-iris\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/portesdesiris.ch\\\/wp-content\\\/uploads\\\/2016\\\/04\\\/1202_PdIR_5837-scaled.jpg\",\"articleSection\":[\"Blog\",\"Entreprises\",\"Ev\u00e9nements\",\"Th\u00e9matiques\"],\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/portesdesiris.ch\\\/de\\\/votre-soiree-dentreprise-a-theme-aux-portes-des-iris\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/portesdesiris.ch\\\/de\\\/votre-soiree-dentreprise-a-theme-aux-portes-des-iris\\\/\",\"url\":\"https:\\\/\\\/portesdesiris.ch\\\/de\\\/votre-soiree-dentreprise-a-theme-aux-portes-des-iris\\\/\",\"name\":\"Exp\u00e9rimentez la nuit polaire spectaculaire aux Portes des Iris - Portes des Iris\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/portesdesiris.ch\\\/de\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/portesdesiris.ch\\\/de\\\/votre-soiree-dentreprise-a-theme-aux-portes-des-iris\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/portesdesiris.ch\\\/de\\\/votre-soiree-dentreprise-a-theme-aux-portes-des-iris\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/portesdesiris.ch\\\/wp-content\\\/uploads\\\/2016\\\/04\\\/1202_PdIR_5837-scaled.jpg\",\"datePublished\":\"2016-04-28T14:35:07+00:00\",\"dateModified\":\"2020-02-05T07:30:36+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/portesdesiris.ch\\\/de\\\/#\\\/schema\\\/person\\\/1fec589d003851c4ffe308e8071bffeb\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/portesdesiris.ch\\\/de\\\/votre-soiree-dentreprise-a-theme-aux-portes-des-iris\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/portesdesiris.ch\\\/de\\\/votre-soiree-dentreprise-a-theme-aux-portes-des-iris\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/portesdesiris.ch\\\/de\\\/votre-soiree-dentreprise-a-theme-aux-portes-des-iris\\\/#primaryimage\",\"url\":\"https:\\\/\\\/portesdesiris.ch\\\/wp-content\\\/uploads\\\/2016\\\/04\\\/1202_PdIR_5837-scaled.jpg\",\"contentUrl\":\"https:\\\/\\\/portesdesiris.ch\\\/wp-content\\\/uploads\\\/2016\\\/04\\\/1202_PdIR_5837-scaled.jpg\",\"width\":1920,\"height\":1280,\"caption\":\"Nuit polaire aux Portes des Iris.\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/portesdesiris.ch\\\/de\\\/votre-soiree-dentreprise-a-theme-aux-portes-des-iris\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/portesdesiris.ch\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Exp\u00e9rimentez la nuit polaire spectaculaire aux Portes des Iris\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/portesdesiris.ch\\\/de\\\/#website\",\"url\":\"https:\\\/\\\/portesdesiris.ch\\\/de\\\/\",\"name\":\"Portes des Iris\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/portesdesiris.ch\\\/de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/portesdesiris.ch\\\/de\\\/#\\\/schema\\\/person\\\/1fec589d003851c4ffe308e8071bffeb\",\"name\":\"Portes des Iris\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/130218f921c4cc9c452a947ae622f180eddde80d56f659695eaebe8acade8074?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/130218f921c4cc9c452a947ae622f180eddde80d56f659695eaebe8acade8074?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/130218f921c4cc9c452a947ae622f180eddde80d56f659695eaebe8acade8074?s=96&d=mm&r=g\",\"caption\":\"Portes des Iris\"},\"url\":\"https:\\\/\\\/portesdesiris.ch\\\/en\\\/author\\\/portesdesiris\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Exp\u00e9rimentez la nuit polaire spectaculaire aux Portes des Iris - Portes des Iris","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/portesdesiris.ch\/de\/votre-soiree-dentreprise-a-theme-aux-portes-des-iris\/","og_locale":"en_US","og_type":"article","og_title":"Exp\u00e9rimentez la nuit polaire spectaculaire aux Portes des Iris - Portes des Iris","og_description":"Quoi de mieux qu&#8217;un d\u00e9cor hivernal et nordique pour\u00a0votre soir\u00e9e de fin d&#8217;ann\u00e9e?\u00a0Aux Portes des Iris, nous vous proposons un environnement\u00a0et une ambiance unique. Imaginez une sc\u00e9nographie tout droit sortie de la Reine des Neiges ou presque. Arriv\u00e9s par la cour dans une for\u00eat de sapins parsem\u00e9e de lumignons givr\u00e9s, vous vous trouverez nez \u00e0 [&hellip;]","og_url":"https:\/\/portesdesiris.ch\/de\/votre-soiree-dentreprise-a-theme-aux-portes-des-iris\/","og_site_name":"Portes des Iris","article_publisher":"https:\/\/www.facebook.com\/portesdesiris\/","article_published_time":"2016-04-28T14:35:07+00:00","article_modified_time":"2020-02-05T07:30:36+00:00","og_image":[{"width":1920,"height":1280,"url":"https:\/\/portesdesiris.ch\/wp-content\/uploads\/2016\/04\/1202_PdIR_5837-scaled.jpg","type":"image\/jpeg"}],"author":"Portes des Iris","twitter_card":"summary_large_image","twitter_misc":{"Written by":"Portes des Iris","Est. reading time":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/portesdesiris.ch\/de\/votre-soiree-dentreprise-a-theme-aux-portes-des-iris\/#article","isPartOf":{"@id":"https:\/\/portesdesiris.ch\/de\/votre-soiree-dentreprise-a-theme-aux-portes-des-iris\/"},"author":{"name":"Portes des Iris","@id":"https:\/\/portesdesiris.ch\/de\/#\/schema\/person\/1fec589d003851c4ffe308e8071bffeb"},"headline":"Exp\u00e9rimentez la nuit polaire spectaculaire aux Portes des Iris","datePublished":"2016-04-28T14:35:07+00:00","dateModified":"2020-02-05T07:30:36+00:00","mainEntityOfPage":{"@id":"https:\/\/portesdesiris.ch\/de\/votre-soiree-dentreprise-a-theme-aux-portes-des-iris\/"},"wordCount":246,"commentCount":0,"image":{"@id":"https:\/\/portesdesiris.ch\/de\/votre-soiree-dentreprise-a-theme-aux-portes-des-iris\/#primaryimage"},"thumbnailUrl":"https:\/\/portesdesiris.ch\/wp-content\/uploads\/2016\/04\/1202_PdIR_5837-scaled.jpg","articleSection":["Blog","Entreprises","Ev\u00e9nements","Th\u00e9matiques"],"inLanguage":"en-US","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/portesdesiris.ch\/de\/votre-soiree-dentreprise-a-theme-aux-portes-des-iris\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/portesdesiris.ch\/de\/votre-soiree-dentreprise-a-theme-aux-portes-des-iris\/","url":"https:\/\/portesdesiris.ch\/de\/votre-soiree-dentreprise-a-theme-aux-portes-des-iris\/","name":"Exp\u00e9rimentez la nuit polaire spectaculaire aux Portes des Iris - Portes des Iris","isPartOf":{"@id":"https:\/\/portesdesiris.ch\/de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/portesdesiris.ch\/de\/votre-soiree-dentreprise-a-theme-aux-portes-des-iris\/#primaryimage"},"image":{"@id":"https:\/\/portesdesiris.ch\/de\/votre-soiree-dentreprise-a-theme-aux-portes-des-iris\/#primaryimage"},"thumbnailUrl":"https:\/\/portesdesiris.ch\/wp-content\/uploads\/2016\/04\/1202_PdIR_5837-scaled.jpg","datePublished":"2016-04-28T14:35:07+00:00","dateModified":"2020-02-05T07:30:36+00:00","author":{"@id":"https:\/\/portesdesiris.ch\/de\/#\/schema\/person\/1fec589d003851c4ffe308e8071bffeb"},"breadcrumb":{"@id":"https:\/\/portesdesiris.ch\/de\/votre-soiree-dentreprise-a-theme-aux-portes-des-iris\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/portesdesiris.ch\/de\/votre-soiree-dentreprise-a-theme-aux-portes-des-iris\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/portesdesiris.ch\/de\/votre-soiree-dentreprise-a-theme-aux-portes-des-iris\/#primaryimage","url":"https:\/\/portesdesiris.ch\/wp-content\/uploads\/2016\/04\/1202_PdIR_5837-scaled.jpg","contentUrl":"https:\/\/portesdesiris.ch\/wp-content\/uploads\/2016\/04\/1202_PdIR_5837-scaled.jpg","width":1920,"height":1280,"caption":"Nuit polaire aux Portes des Iris."},{"@type":"BreadcrumbList","@id":"https:\/\/portesdesiris.ch\/de\/votre-soiree-dentreprise-a-theme-aux-portes-des-iris\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/portesdesiris.ch\/en\/"},{"@type":"ListItem","position":2,"name":"Exp\u00e9rimentez la nuit polaire spectaculaire aux Portes des Iris"}]},{"@type":"WebSite","@id":"https:\/\/portesdesiris.ch\/de\/#website","url":"https:\/\/portesdesiris.ch\/de\/","name":"Portes des Iris","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/portesdesiris.ch\/de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Person","@id":"https:\/\/portesdesiris.ch\/de\/#\/schema\/person\/1fec589d003851c4ffe308e8071bffeb","name":"Portes des Iris","image":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/secure.gravatar.com\/avatar\/130218f921c4cc9c452a947ae622f180eddde80d56f659695eaebe8acade8074?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/130218f921c4cc9c452a947ae622f180eddde80d56f659695eaebe8acade8074?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/130218f921c4cc9c452a947ae622f180eddde80d56f659695eaebe8acade8074?s=96&d=mm&r=g","caption":"Portes des Iris"},"url":"https:\/\/portesdesiris.ch\/en\/author\/portesdesiris\/"}]}},"_links":{"self":[{"href":"https:\/\/portesdesiris.ch\/en\/wp-json\/wp\/v2\/posts\/1131","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/portesdesiris.ch\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/portesdesiris.ch\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/portesdesiris.ch\/en\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/portesdesiris.ch\/en\/wp-json\/wp\/v2\/comments?post=1131"}],"version-history":[{"count":0,"href":"https:\/\/portesdesiris.ch\/en\/wp-json\/wp\/v2\/posts\/1131\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/portesdesiris.ch\/en\/wp-json\/wp\/v2\/media\/9007"}],"wp:attachment":[{"href":"https:\/\/portesdesiris.ch\/en\/wp-json\/wp\/v2\/media?parent=1131"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/portesdesiris.ch\/en\/wp-json\/wp\/v2\/categories?post=1131"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/portesdesiris.ch\/en\/wp-json\/wp\/v2\/tags?post=1131"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}